{"id":14908,"date":"2018-06-14T03:00:32","date_gmt":"2018-06-14T02:00:32","guid":{"rendered":"https:\/\/www.saporedicina.com\/es\/?p=14908"},"modified":"2022-02-14T19:09:53","modified_gmt":"2022-02-14T18:09:53","slug":"investigacion-china","status":"publish","type":"post","link":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/","title":{"rendered":"Investigaci\u00f3n en China &#8211; Pros y Contras de investigar en China"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg\" alt=\"Investigaci\u00f3n en China\" width=\"700\" height=\"376\" class=\"aligncenter size-full wp-image-14910\" srcset=\"https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg 700w, https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china-300x161.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>Durante la crisis econ\u00f3mica mundial las pol\u00edticas de austeridad de muchos pa\u00edses afectaron los presupuestos del sector de I+D y pese a la incipiente recuperaci\u00f3n de los \u00faltimos a\u00f1os la <a href=\"https:\/\/elpais.com\/elpais\/2018\/04\/11\/ciencia\/1523449792_401044.html\" rel=\"noopener noreferrer\" target=\"_blank\">I+D sigue en niveles m\u00ednimos<\/a>. <\/p>\n<p>Durante los \u00faltimos a\u00f1os muchos investigadores se han visto forzados a abandonar sus pa\u00edses y probar suerte en lugares con m\u00e1s perspectivas. Algunos incluso se habr\u00e1n planteado la posibilidad de emigrar a China. Este art\u00edculo est\u00e1 dedicado a exponer de forma breve los pros y los contras del sistema de investigaci\u00f3n chino.<\/p>\n<p><strong><!--more--><\/strong><\/p>\n<h2>Pros de hacer investigaci\u00f3n en China<\/h2>\n<ul>\n<li><strong>China ha aumentado su presupuesto dedicado a la investigaci\u00f3n de forma exponencial en la \u00faltima decada<\/strong>. Este esfuerzo econ\u00f3mico se ha traducido en que por el momento China esta situada en la <a href=\"https:\/\/www.scimagojr.com\/countryrank.php\" title=\"SCImago Country Rankings\" target=\"_blank\" rel=\"noopener noreferrer\">segunda posici\u00f3n mundial en cuanto a n\u00famero de publicaciones cient\u00edficas<\/a>.<\/li>\n<\/ul>\n<p><strong><!--more--><\/strong><\/p>\n<ul>\n<li><strong>China dispone de cientos de centros de I+D equipados con las \u00faltimas tecnolog\u00edas disponibles en el mercado<\/strong>, asegurando las condiciones necesarias para desarrollar una investigaci\u00f3n de alto nivel.<\/li>\n<\/ul>\n<ul>\n<li>Actualmente, <strong>China tiene una gran demanda de especialistas, sobretodo en \u00e1mbitos de formaci\u00f3n e investigaci\u00f3n<\/strong>. Por este motivo encontrar una posici\u00f3n o trabajo en estos campos es relativamente f\u00e1cil. Adem\u00e1s, el hecho de que por el momento no haya muchos investigadores extranjeros que hayan decidido dar este paso, abre la posibilidad de convertirse en un importante puente de comunicaci\u00f3n entre occidente y China.<\/li>\n<\/ul>\n<ul>\n<li>Al contrario de lo que sucede en muchos pa\u00edses, <strong>China cuenta con un elevado n\u00famero de personal investigador y de soporte<\/strong>. Es muy frecuente encontrar  grupos de investigaci\u00f3n que cuentan con m\u00e1s de  20 miembros.<\/li>\n<\/ul>\n<ul>\n<li>Debido a que China realiza una parte importante de la producci\u00f3n manufacturera mundial, los <strong>costes de la mayor\u00eda de consumibles<\/strong> (especialmente en investigaciones que requieren trabajo de laboratorio) se reducen sustancialmente y son suministrados en periodos de tiempo extremadamente cortos.<\/li>\n<\/ul>\n<ul>\n<li>En estos momentos, se ofrecen <strong>incentivos econ\u00f3micos por publicaciones<\/strong>.  Cuando se publica un art\u00edculo el autor o autores van a recibir un dinero  extra que va a variar seg\u00fan el \u00edndice de impacto de la publicaci\u00f3n.<\/li>\n<\/ul>\n<ul>\n<li>Tampoco no se deber\u00eda menospreciar la <strong><a href=\"https:\/\/www.saporedicina.com\/es\/como-aprender-chino\/\" title=\"C\u00f3mo aprender chino desde casa\" >posibilidad de aprender el chino<\/a><\/strong>, un idioma que puede abrir muchas puertas profesionales.<\/li>\n<\/ul>\n<h2>Contras de hacer investigaci\u00f3n en China<\/h2>\n<p>Hay mucha gente que puede llegar a pensar que al ir a China va ser recibido como una \u00abestrella\u00bb, le van a proporcionar gran cantidad de dinero y personal y con sus ideas va a poder publicar cientos de art\u00edculos y patentes.<\/p>\n<p>Sin embargo, la realidad es difiere bastante de esta idea. A continuaci\u00f3n voy a exponer algunos de los principales problemas que se pueden encontrar una vez en China.<\/p>\n<ul>\n<li><strong>China no es apta para todo el mundo<\/strong>: Tiene una cultura y unas costumbres que a muchos les pueden resultar extra\u00f1as e incluso molestas. Un claro ejemplo, que puede afectar nuestras relaciones laborales, es la \u00ab<a href=\"https:\/\/www.china-mike.com\/chinese-culture\/understanding-chinese-mind\/cult-of-face\/\" title=\"THE CULT OF \u201cFACE\u201d\" target=\"_blank\" rel=\"noopener noreferrer\">cultura de la cara<\/a>\u00ab. La \u00abcultura de la carta\u00bb les impide reconocer que han cometido un error, que no han entendido algo o que simplemente no saben algo. <\/li>\n<\/ul>\n<ul>\n<li>\n<p><strong>Los salarios son comparativamente bastante bajos<\/strong>: El <a href=\"https:\/\/www.saporedicina.com\/es\/estudiar-beca-china\/\" rel=\"noopener noreferrer\" target=\"_blank\">salario est\u00e1ndar para un doctorando<\/a> es  alrededor de 2.500 Yuan al mes (unos 350\u20ac), para un posdoctoral o profesor asociado de primer nivel  unos 4.000-5.000 Yuan al mes (500\u20ac-650\u20ac) y para un investigador principal alrededor de 10.000 Yuan (1.300 \u20ac) aunque en este caso puede variar mucho dependiendo del curriculum, la posici\u00f3n y la universidad.<\/p>\n<p>Sin embargo muchas universidades, y en especial <a href=\"http:\/\/english.cas.cn\/\" title=\"Chinese Academy of Sciences\" target=\"_blank\" rel=\"noopener noreferrer\">La Academia de las Ciencias Chinas (CAS)<\/a>, est\u00e1n proporcionando complementos a estos salarios para tratar de retener el talento (normalmente a partir de la etapa posdoctoral), de esta forma los salarios se equiparan a los salarios est\u00e1ndar internacionales. Adem\u00e1s, los contratos de investigaci\u00f3n ofrecen una serie de ventajas como un <a href=\"https:\/\/www.saporedicina.com\/es\/seguro-medico-china-expatriados\/\" rel=\"noopener noreferrer\" target=\"_blank\">seguro de salud<\/a>, alojamiento a muy <a href=\"https:\/\/www.saporedicina.com\/es\/coste-de-vida-en-china\/\" rel=\"noopener noreferrer\" target=\"_blank\">por debajo del precio de mercado<\/a> y la posibilidad de comer en cantinas fuertemente subvencionadas.<\/p>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>El sistema de investigaci\u00f3n chino es, en general, extremadamente ineficiente y en algunos casos de dudosa calidad.<\/strong> Esto se hace patente cuando se analiza la <a href=\"https:\/\/www.scimagojr.com\/countryrank.php?order=h&#038;ord=desc\" target=\"_blank\" rel=\"noopener noreferrer\">cantidad de art\u00edculos considerados de calidad<\/a>, en este caso China cae a la posici\u00f3n 13 pese a tener un presupuesto y una infraestructura para estar en las primeras posiciones. Este fen\u00f3meno es principalmente debido a la abultada burocracia, la juventud del sistema chino de investigaci\u00f3n y el <a href=\"http:\/\/www.zaichina.net\/2010\/06\/11\/una-educacion-sin-corazon\/\" title=\"Una educaci\u00f3n sin coraz\u00f3n\" target=\"_blank\" rel=\"noopener noreferrer\">sistema educativo<\/a> (d\u00f3nde se penaliza la creatividad).<\/li>\n<\/ul>\n<ul>\n<li>Relacionado con el punto anterior, <strong>la falta de creatividad es compensada con la cantidad<\/strong> por lo que la filosof\u00eda de muchos grupos de investigaci\u00f3n esta basada en hacer mucho trabajo sin una direcci\u00f3n muy concreta con la esperanza de que algo sea de utilidad. Por esta raz\u00f3n se da muy poco valor individual al personal investigador. <\/li>\n<\/ul>\n<ul>\n<li><strong>El sistema de investigaci\u00f3n Chino es muy cerrado<\/strong>, de dif\u00edcil acceso a extranjeros y consecuentemente falto de internacionalidad. Esto puede llegar a ser una ventaja si se consigue entrar en el sistema, pero en la mayor\u00eda de casos supone un problema ya que es muy com\u00fan que los extranjeros que se sientan aislados.<\/li>\n<\/ul>\n<ul>\n<li>El idioma es otro punto a tener en cuenta. Aprender el chino no es f\u00e1cil y <strong>en general el nivel de ingl\u00e9s del personal investigador es relativamente bajo<\/strong>. Esta es tambi\u00e9n una de las razones por las que entrar en el sistema puede resultar tan dif\u00edcil.<\/li>\n<\/ul>\n<ul>\n<li><strong>Internet<\/strong> es uno de los dolores de cabeza que nos enfrentamos todos los profesionales aqu\u00ed en China. Por lo general los sitios web de b\u00fasqueda bibliogr\u00e1fica e otros sitios indispensables para la investigaci\u00f3n no est\u00e1n bloqueados en China. Sin embrago, <a href=\"https:\/\/www.saporedicina.com\/es\/internet-china\/\" rel=\"noopener noreferrer\" target=\"_blank\">la navegaci\u00f3n en sitios web no chinos es con frecuencia muy lenta e inestable<\/a>, dificultando mucho el trabajo. <\/li>\n<\/ul>\n<h2>Consideraciones finales<\/h2>\n<p>Aunque muchos de los argumentos puedan sonar a t\u00f3pico, es una realidad que he experimentado en los cinco a\u00f1os que pas\u00e9 en el sistema de investigaci\u00f3n chino. <\/p>\n<p><strong>China tiene mucho potencial pero para explotarlo se necesita perseverancia<\/strong>. Aunque cada vez hay m\u00e1s gente interesada en este pa\u00eds a\u00fan muy pocos han sido capaces de realmente entrar en su sistema, por lo que la recompensa bien puede merecer el esfuerzo. <\/p>\n<p><span class=\"credits\">Photo Credits: Photo by <a href=\"https:\/\/pixabay.com\/photos\/shelf-rack-bookcase-indoors-3169790\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">BachBackpack<\/a> on <a href=\"https:\/\/pixabay.com\/service\/license\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Pixabay<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la crisis econ\u00f3mica mundial las pol\u00edticas de austeridad de muchos pa\u00edses afectaron los presupuestos del sector de I+D y pese a la incipiente recuperaci\u00f3n de los \u00faltimos a\u00f1os la I+D sigue en niveles m\u00ednimos. Durante los \u00faltimos a\u00f1os muchos investigadores se han visto forzados a abandonar sus pa\u00edses y probar suerte en lugares con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[14],"tags":[87],"class_list":["post-14908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trabajar-en-china","tag-trabajar-en-china"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investigaci\u00f3n en China - Pros y Contras de investigar en China<\/title>\n<meta name=\"description\" content=\"China puede ser un buen destino para progresar en la carrera investigadora, pero \u00bfsabes lo que vas a encontrarte? Aqu\u00ed encontrar\u00e1s algunos puntos clave\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.saporedicina.com\/es\/investigacion-china\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investigaci\u00f3n en China - Pros y Contras de investigar en China\" \/>\n<meta property=\"og:description\" content=\"China puede ser un buen destino para progresar en la carrera investigadora, pero \u00bfsabes lo que vas a encontrarte? Aqu\u00ed encontrar\u00e1s algunos puntos clave\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.saporedicina.com\/es\/investigacion-china\/\" \/>\n<meta property=\"og:site_name\" content=\"Sapore di Cina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/saporedicinaespanol\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SaporeDiCinaEspanol\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-14T02:00:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-14T18:09:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"376\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sapore di Cina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SbortoZhou\" \/>\n<meta name=\"twitter:site\" content=\"@sbortozhou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sapore di Cina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/\"},\"author\":{\"name\":\"Sapore di Cina\",\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/#\\\/schema\\\/person\\\/45e32f0753ff39fdff0a09c9cc5d8025\"},\"headline\":\"Investigaci\u00f3n en China &#8211; Pros y Contras de investigar en China\",\"datePublished\":\"2018-06-14T02:00:32+00:00\",\"dateModified\":\"2022-02-14T18:09:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/\"},\"wordCount\":1089,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/investigacion-china.jpg\",\"keywords\":[\"Trabajar en China\"],\"articleSection\":[\"Trabajar en China\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/\",\"url\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/\",\"name\":\"Investigaci\u00f3n en China - Pros y Contras de investigar en China\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/investigacion-china.jpg\",\"datePublished\":\"2018-06-14T02:00:32+00:00\",\"dateModified\":\"2022-02-14T18:09:53+00:00\",\"description\":\"China puede ser un buen destino para progresar en la carrera investigadora, pero \u00bfsabes lo que vas a encontrarte? Aqu\u00ed encontrar\u00e1s algunos puntos clave\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/investigacion-china.jpg\",\"contentUrl\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/investigacion-china.jpg\",\"width\":700,\"height\":376,\"caption\":\"Investigaci\u00f3n en China\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/investigacion-china\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"SDC\",\"item\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investigaci\u00f3n en China &#8211; Pros y Contras de investigar en China\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/\",\"name\":\"Sapore di Cina\",\"description\":\"Aprender Chino, Viajar, Estudiar o Trabajar en China y Asia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/#organization\"},\"alternateName\":\"SDC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/#organization\",\"name\":\"Sapore di Cina\",\"url\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.jpg\",\"width\":800,\"height\":800,\"caption\":\"Sapore di Cina\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/saporedicinaespanol\",\"https:\\\/\\\/x.com\\\/sbortozhou\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCl2ssfXqNmOeaY6l470UDlQ\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/#\\\/schema\\\/person\\\/45e32f0753ff39fdff0a09c9cc5d8025\",\"name\":\"Sapore di Cina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca26314d288417a1aec0ab0d68aabfac9f87f67b21e5b472e3ef645cd8f4803?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca26314d288417a1aec0ab0d68aabfac9f87f67b21e5b472e3ef645cd8f4803?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca26314d288417a1aec0ab0d68aabfac9f87f67b21e5b472e3ef645cd8f4803?s=96&d=mm&r=g\",\"caption\":\"Sapore di Cina\"},\"description\":\"Sapore di Cina es un sitio web que proporciona informaci\u00f3n de primera mano sobre vivir y viajar en China y el sudeste asi\u00e1tico. Puede leer la p\u00e1gina sobre nosotros para obtener m\u00e1s informaci\u00f3n.\",\"sameAs\":[\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/SaporeDiCinaEspanol\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/saporedicina\",\"https:\\\/\\\/x.com\\\/SbortoZhou\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCl2ssfXqNmOeaY6l470UDlQ\"],\"url\":\"https:\\\/\\\/www.saporedicina.com\\\/es\\\/author\\\/sborto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investigaci\u00f3n en China - Pros y Contras de investigar en China","description":"China puede ser un buen destino para progresar en la carrera investigadora, pero \u00bfsabes lo que vas a encontrarte? Aqu\u00ed encontrar\u00e1s algunos puntos clave","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/","og_locale":"es_ES","og_type":"article","og_title":"Investigaci\u00f3n en China - Pros y Contras de investigar en China","og_description":"China puede ser un buen destino para progresar en la carrera investigadora, pero \u00bfsabes lo que vas a encontrarte? Aqu\u00ed encontrar\u00e1s algunos puntos clave","og_url":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/","og_site_name":"Sapore di Cina","article_publisher":"https:\/\/www.facebook.com\/saporedicinaespanol","article_author":"https:\/\/www.facebook.com\/SaporeDiCinaEspanol\/","article_published_time":"2018-06-14T02:00:32+00:00","article_modified_time":"2022-02-14T18:09:53+00:00","og_image":[{"width":700,"height":376,"url":"https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg","type":"image\/jpeg"}],"author":"Sapore di Cina","twitter_card":"summary_large_image","twitter_creator":"@SbortoZhou","twitter_site":"@sbortozhou","twitter_misc":{"Escrito por":"Sapore di Cina","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/#article","isPartOf":{"@id":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/"},"author":{"name":"Sapore di Cina","@id":"https:\/\/www.saporedicina.com\/es\/#\/schema\/person\/45e32f0753ff39fdff0a09c9cc5d8025"},"headline":"Investigaci\u00f3n en China &#8211; Pros y Contras de investigar en China","datePublished":"2018-06-14T02:00:32+00:00","dateModified":"2022-02-14T18:09:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/"},"wordCount":1089,"commentCount":0,"publisher":{"@id":"https:\/\/www.saporedicina.com\/es\/#organization"},"image":{"@id":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/#primaryimage"},"thumbnailUrl":"https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg","keywords":["Trabajar en China"],"articleSection":["Trabajar en China"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.saporedicina.com\/es\/investigacion-china\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/","url":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/","name":"Investigaci\u00f3n en China - Pros y Contras de investigar en China","isPartOf":{"@id":"https:\/\/www.saporedicina.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/#primaryimage"},"image":{"@id":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/#primaryimage"},"thumbnailUrl":"https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg","datePublished":"2018-06-14T02:00:32+00:00","dateModified":"2022-02-14T18:09:53+00:00","description":"China puede ser un buen destino para progresar en la carrera investigadora, pero \u00bfsabes lo que vas a encontrarte? Aqu\u00ed encontrar\u00e1s algunos puntos clave","breadcrumb":{"@id":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.saporedicina.com\/es\/investigacion-china\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/#primaryimage","url":"https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg","contentUrl":"https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg","width":700,"height":376,"caption":"Investigaci\u00f3n en China"},{"@type":"BreadcrumbList","@id":"https:\/\/www.saporedicina.com\/es\/investigacion-china\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"SDC","item":"https:\/\/www.saporedicina.com\/es\/"},{"@type":"ListItem","position":2,"name":"Investigaci\u00f3n en China &#8211; Pros y Contras de investigar en China"}]},{"@type":"WebSite","@id":"https:\/\/www.saporedicina.com\/es\/#website","url":"https:\/\/www.saporedicina.com\/es\/","name":"Sapore di Cina","description":"Aprender Chino, Viajar, Estudiar o Trabajar en China y Asia","publisher":{"@id":"https:\/\/www.saporedicina.com\/es\/#organization"},"alternateName":"SDC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.saporedicina.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.saporedicina.com\/es\/#organization","name":"Sapore di Cina","url":"https:\/\/www.saporedicina.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.saporedicina.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2019\/04\/logo.jpg","contentUrl":"https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2019\/04\/logo.jpg","width":800,"height":800,"caption":"Sapore di Cina"},"image":{"@id":"https:\/\/www.saporedicina.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/saporedicinaespanol","https:\/\/x.com\/sbortozhou","https:\/\/www.youtube.com\/channel\/UCl2ssfXqNmOeaY6l470UDlQ\/"]},{"@type":"Person","@id":"https:\/\/www.saporedicina.com\/es\/#\/schema\/person\/45e32f0753ff39fdff0a09c9cc5d8025","name":"Sapore di Cina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca26314d288417a1aec0ab0d68aabfac9f87f67b21e5b472e3ef645cd8f4803?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca26314d288417a1aec0ab0d68aabfac9f87f67b21e5b472e3ef645cd8f4803?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca26314d288417a1aec0ab0d68aabfac9f87f67b21e5b472e3ef645cd8f4803?s=96&d=mm&r=g","caption":"Sapore di Cina"},"description":"Sapore di Cina es un sitio web que proporciona informaci\u00f3n de primera mano sobre vivir y viajar en China y el sudeste asi\u00e1tico. Puede leer la p\u00e1gina sobre nosotros para obtener m\u00e1s informaci\u00f3n.","sameAs":["https:\/\/www.saporedicina.com\/es\/","https:\/\/www.facebook.com\/SaporeDiCinaEspanol\/","https:\/\/www.linkedin.com\/company\/saporedicina","https:\/\/x.com\/SbortoZhou","https:\/\/www.youtube.com\/channel\/UCl2ssfXqNmOeaY6l470UDlQ"],"url":"https:\/\/www.saporedicina.com\/es\/author\/sborto\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg",700,376,false],"thumbnail":["https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china-150x150.jpg",150,150,true],"medium":["https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china-300x161.jpg",300,161,true],"medium_large":["https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg",700,376,false],"large":["https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg",700,376,false],"1536x1536":["https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg",700,376,false],"2048x2048":["https:\/\/www.saporedicina.com\/es\/wp-content\/uploads\/2018\/06\/investigacion-china.jpg",700,376,false]},"uagb_author_info":{"display_name":"Sapore di Cina","author_link":"https:\/\/www.saporedicina.com\/es\/author\/sborto\/"},"uagb_comment_info":0,"uagb_excerpt":"Durante la crisis econ\u00f3mica mundial las pol\u00edticas de austeridad de muchos pa\u00edses afectaron los presupuestos del sector de I+D y pese a la incipiente recuperaci\u00f3n de los \u00faltimos a\u00f1os la I+D sigue en niveles m\u00ednimos. Durante los \u00faltimos a\u00f1os muchos investigadores se han visto forzados a abandonar sus pa\u00edses y probar suerte en lugares con&hellip;","_links":{"self":[{"href":"https:\/\/www.saporedicina.com\/es\/wp-json\/wp\/v2\/posts\/14908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saporedicina.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saporedicina.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saporedicina.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saporedicina.com\/es\/wp-json\/wp\/v2\/comments?post=14908"}],"version-history":[{"count":0,"href":"https:\/\/www.saporedicina.com\/es\/wp-json\/wp\/v2\/posts\/14908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saporedicina.com\/es\/wp-json\/wp\/v2\/media\/14910"}],"wp:attachment":[{"href":"https:\/\/www.saporedicina.com\/es\/wp-json\/wp\/v2\/media?parent=14908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saporedicina.com\/es\/wp-json\/wp\/v2\/categories?post=14908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saporedicina.com\/es\/wp-json\/wp\/v2\/tags?post=14908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}